{"id":30,"count":1,"description":"","link":"https:\/\/battery-lab.green-energy.co.jp\/find\/category\/%e6%9d%b1%e5%8c%97%e9%9b%bb%e5%8a%9b%e7%ae%a1%e5%86%85\/","name":"\u6771\u5317\u96fb\u529b\u7ba1\u5185","slug":"%e6%9d%b1%e5%8c%97%e9%9b%bb%e5%8a%9b%e7%ae%a1%e5%86%85","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/battery-lab.green-energy.co.jp\/find\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/battery-lab.green-energy.co.jp\/find\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/battery-lab.green-energy.co.jp\/find\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/battery-lab.green-energy.co.jp\/find\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}